{"id":1570,"date":"2023-11-16T18:11:51","date_gmt":"2023-11-16T17:11:51","guid":{"rendered":"https:\/\/nuovo.verdeblu.com\/?post_type=product&#038;p=1570"},"modified":"2025-04-17T11:45:33","modified_gmt":"2025-04-17T09:45:33","slug":"aslec","status":"publish","type":"product","link":"https:\/\/verdeblu.com\/it\/aslec\/","title":{"rendered":"Aslec 4"},"content":{"rendered":"<p><strong>ASLEC 4<\/strong>\/ Yacht a Noleggio<\/p>\n<p>ASLEC 4 \u00e9 un meraviglioso Superyacht semidislocante di 48 metri che effettua Noleggio di Lusso on Equipaggio,  varato dal cantiere italiano Rossi Navi nel 2012.<br \/> Lo yacht \u00e9 caratterizzato da ampi spazi esterni e da una distintiva prora dritta. Scafo in acciaio e sovrastruttura in lega leggera marina.<br \/>\nAslec 4 sottolinea le priorit\u00e0 odierne dell&#8217;industria nautica: rispetto dell&#8217;ambiente:  essere economici ed efficienti senza essere inutilmente ingombranti.<br \/>\nLo yacht ha linee morbide e voluminose, queste sono solo alcune delle sue principali risorse. Questo senso di spazio diventa immediatamente evidente all&#8217;imbarco, dove un ponte di poppa di 70 metri quadrati di dimensioni impressionanti accoglie gli ospiti a bordo.<br \/>\nGli interni, disegnati da R\u00e9mi Tessier Design sono luminosi e  curati nel minimo dettaglio dando ampia attenzione alla scelta dei materiali; molti dettagli sono stati ideati con fibre di carbonio, prezioso cromo nero e soprattutto dalla foglia oro che riveste gran parte dei soffitti e delle pareti. Una sintesi perfetta tra lussuosa raffinatezza e allure contemporanea. <\/p>\n<p>Estrema cura \u00e8 stata data anche all\u2019intrattenimento di bordo del Rossinavi, un impianto audio video con controllo globale estremamente intuitivo nell\u2019utilizzo. Sistema Kaleidescape per l\u2019on-demand, Lutron per la gestione domotica ed il sistema Apple con AirPlay integrato per il completo controllo dell\u2019audio.<\/p>\n<p><strong>Sistemazioone ospiti<\/strong>: Aslec 4 ospita 10 persone in 5 suite di lusso, con la master suite, 2 suites doppie e comode cabine twin queste ultime ciascuna con un letto pullman extra (pi\u00f9 adatto per bambini).<br \/>\nAl piano superiore, il Sun Deck completa perfettamente la gamma di servizi di lusso del Superyacht  Aslec 4, fedele alla forma con un ampio spazio sul ponte e una grande vasca idromassaggio come punto focale e attrattiva principale.<\/p>\n<p>Il Superyacht ASLEC 4 effettua Noleggio di Lusso con equipaggio  anche in Francia e Corsica ma essendo uno yacht a Noleggio Occasionale, per legge l&#8217;imbarco dovr\u00e0 essere in Italia (lo sbarco ovunque)<\/p>\n<p><strong>Equipaggio<\/strong>: Lo yacht ha 9 membri equipaggio ed \u00e9 condotto dal Comandante Romano Picchianti, e altri 8 membri tra cui la brava e talentuosa Chef Elena Buglione. <\/p>\n<p>Guarda il Sito web:\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=8NOpZwTVt1c&amp;feature=youtu.be%22\" target=\"_blank\" rel=\"noopener\">Visit Yach AslecIV<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-weight: bold\">Bassa Stagione:<\/span> 180.000 \u20ac\/sett<br \/>\n<span style=\"font-weight: bold\">Alta Stagione:<\/span> 265.000 \u20ac\/sett<br \/>\n<span style=\"font-weight: bold\">Media Stagione:<\/span> 215.000 \u20ac\/sett<br \/>\n<span style=\"font-weight: bold\">Lunghezza mt:<\/span> 48<br \/>\n<span style=\"font-weight: bold\">Cabine:<\/span> 5\u00a0 &#8211; <strong>Crew: <\/strong>9<br \/>\n<span style=\"font-weight: bold\">Tipo di Yacht:<\/span> Motor Yacht<br \/>\n<span style=\"font-weight: bold\">Anno:<\/span> 2012 &#8211; Refit 2017\/2021<br \/>\n<span style=\"font-weight: bold\">Cantiere: <\/span>RossiNavi<\/p>\n","protected":false},"featured_media":1571,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[]},"product_cat":[88,1125,81,103,1123,98,77,76,128,90,22,100,1101,102,101,114,89,56,127,87,40,112,126,108,1017,772,82,939,99,1124,113,94,97,92,118,45,47],"product_tag":[498,842,522,1102,912],"class_list":["post-1570","product","type-product","status-publish","has-post-thumbnail","product_cat-noleggio-yacht-arcipelago-toscano","product_cat-noleggio-yacht-argentario","product_cat-noleggio-yacht-bonifacio","product_cat-noleggio-yacht-capraia","product_cat-noleggio-yacht-capri","product_cat-noleggio-yacht-cinque-terre","product_cat-noleggio-yacht-corsica","product_cat-noleggio-yacht-costa-azzurra","product_cat-noleggio-yacht-costa-smeralda","product_cat-noleggio-yacht-costiera-amalfitana","product_cat-destinazioni-yacht","product_cat-noleggio-yacht-elba","product_cat-noleggio-yacht-genova","product_cat-noleggio-yacht-giannutri","product_cat-noleggio-yacht-giglio","product_cat-noleggio-yacht-ischia","product_cat-noleggio-yacht-isole-pontine","product_cat-noleggio-yacht-italia","product_cat-noleggio-yacht-la-maddalena","product_cat-noleggio-yacht-liguria","product_cat-noleggio-yacht-mediterraneo","product_cat-noleggio-yacht-napoli","product_cat-noleggio-yacht-olbia","product_cat-noleggio-yacht-palmarola","product_cat-noleggio-yacht-ponza","product_cat-noleggio-yacht-porto-cervo","product_cat-noleggio-yacht-porto-vecchio","product_cat-noleggio-yacht-portofino","product_cat-noleggio-yacht-portovenere","product_cat-noleggio-yacht-positano","product_cat-noleggio-yacht-procida","product_cat-noleggio-yacht-sanremo","product_cat-noleggio-yacht-santa-margherita","product_cat-noleggio-yacht-sardegna","product_cat-noleggio-yacht-sorrento","product_cat-tipologie-yacht","product_cat-noleggio-yacht-motore","product_tag-34mt-50mt","product_tag-superyacht","product_tag-yacht-a-motore","product_tag-yacht-con-equipaggio","product_tag-yacht-di-lusso","pa_cantieri-rossi-navi","pa_lunghezza-48-mt","desktop-align-left","tablet-align-left","mobile-align-left","first","instock","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/verdeblu.com\/it\/wp-json\/wp\/v2\/product\/1570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verdeblu.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/verdeblu.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/verdeblu.com\/it\/wp-json\/wp\/v2\/media\/1571"}],"wp:attachment":[{"href":"https:\/\/verdeblu.com\/it\/wp-json\/wp\/v2\/media?parent=1570"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/verdeblu.com\/it\/wp-json\/wp\/v2\/product_cat?post=1570"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/verdeblu.com\/it\/wp-json\/wp\/v2\/product_tag?post=1570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}